{"id":65,"date":"2010-03-05T15:15:59","date_gmt":"2010-03-05T14:15:59","guid":{"rendered":"http:\/\/www.alice-miller.com\/de\/?p=65"},"modified":"2015-10-09T15:19:01","modified_gmt":"2015-10-09T14:19:01","slug":"ironie-als-abwehr","status":"publish","type":"post","link":"http:\/\/www.alice-miller.com\/de\/ironie-als-abwehr\/","title":{"rendered":"Ironie als Abwehr"},"content":{"rendered":"<div class=\"colonne-droite\">\n<h1>Friday 05 March 2010<\/h1>\n<h2>Ironie als Abwehr<\/h2>\n<p>Sehr geehrte Frau Miller,<\/p>\n<p>vielen Dank einmal f\u00fcr all ihre B\u00fccher. Sie sind eine Art Gesundbrunnen f\u00fcr mich, trostspendend, eine gro\u00dfe Hilfe. Das erste von vielen &#8222;Therapie- und Psychologieb\u00fcchern&#8220; in meinem Leben war das Drama-Buch, wobei ich sagen muss, dass ich mich zun\u00e4chst gar nicht angesprochen gef\u00fchlt hatte, da &#8222;begabtes Kind&#8220; irgendwie nach Genie, a la Mozart klang &#8211; und so sah ich mich nicht&#8230; Ich habe es dann doch gelesen und gleichzeitig das gro\u00dfe Gl\u00fcck gehabt, eine Therapeutin zu haben die ebenfalls bedingungslos auf meiner Seite stand und die mir eine Perspektive auf die emotionale Atmosph\u00e4re in meiner Familie erm\u00f6glichte, die mir zuvor ganz unm\u00f6glich gewesen w\u00e4re. Das Bezeugende Gegen\u00fcber als Hilfe ist sehr! wichtig.<\/p>\n<p>Leider muss ich heute sagen, dass ich mein Leben ganz und gar in der Situation zwischen den Polen Grandiosit\u00e4t und Depression fristete und teilweise heute noch friste&#8230;<br \/>\nDa nie etwas je genug war, die Leere f\u00fcllte, st\u00fcrzte ich mich in ein naturwissenschaftliches Studium und tat mich gleichzeitig noch als eine Art Zirkusartist\/Entertainer\/Clown und Stra\u00dfenk\u00fcnstler hervor. Verdiente als Student jahrelang f\u00fcr mein Gef\u00fchl recht viel Geld und habe Jahre wie in einer Art Rausch oder High verbracht. (Allerdings hatte ich auch schon mit 25 einen schweren depressiven Einbruch mit Klinikaufenthalt&#8230;)<br \/>\nDa ich nie wirklich erwachsen, in mir selbst geerdet (Echtheit der eigenen Gef\u00fchle&#8230;) war, war es mir unm\u00f6glich etwa in der Chemie beruflich tats\u00e4chlich Fu\u00df zu fassen. Die Kunst, Theater, Comedy wurde zum Hauptthema, jedoch f\u00fchlte ich mich auch hier nie gl\u00fccklich entspannt angekommen, sondern war immer nur so gut wie der letzte Auftritt&#8230;<\/p>\n<p>In der Tat war es f\u00fcr mich wie in dem schon angestaubt wirkenden Klischee: Ich machte alle Menschen gl\u00fccklich &#8211; nur mich nicht&#8230; sehr traurig. Wirklich ich habe \u00fcber Jahre und immer Kinderaugen zum Strahlen gebracht und P\u00e4rchen ihr Flanieren \u00fcber die Promenade in den Ostseeb\u00e4dern vers\u00fc\u00dft&#8230; Nur ich selbst f\u00fchlte mich am n\u00e4chsten Morgen leer depressiv und allein. Gleichzeit war ich auf der B\u00fchne auf bizarre Weise so entspannt wie sonst nie, alle Unruhe legt sich, man ist voll konzentriert auf einen Punkt gesammelt. Ein voller Genuss..<\/p>\n<p>Ich w\u00fcrde das heute in Analogie zu Drogensucht sehen, nur dass die Droge (Adrenalin) immer K\u00f6rper erzeugt wird anstatt eingenommen&#8230;<\/p>\n<p>Heute kann ich nur jedes Detail, was sie beschreiben, insbesondere zum Thema Kunst, Kultur so sehr best\u00e4tigen. 99% des Betriebs erscheinen mir als spektakul\u00e4re Schaumschl\u00e4gerei, Vernebelungsaktionen allerorten, die Welt ist auf der Flucht. das Publikum goutiert die Produkte denn es ist auch auf der Flucht&#8230; Seit langem wei\u00df ich dass es diesen Unterschied gibt zwischen der Kunst aus der Neurose und der Kunst aus der Trauerarbeit.<\/p>\n<p>Und doch m\u00fcsste ich l\u00fcgen wenn ich sagen wollte ich h\u00e4tte mich tats\u00e4chlich befreit&#8230; ich durchschaue die alten Mechanismen aber habe gro\u00dfe Angst vor selbst\u00e4ndigen erwachsenen Schritten, Schritten in Unabh\u00e4ngigkeit, in Eigenverantwortung.<\/p>\n<p>Immer wieder sto\u00dfe ich auf den Punkt: Der Grund warum ich in der Kunst bin (war) ist wirklich die Sache der Bewunderung durch andere gewesen&#8230; abgesehen davon interessiert es mich gar nicht so&#8230; Und jetzt? wie weiter?<br \/>\nEhrlich gesagt, mein gr\u00f6\u00dfter Wunsch ist es keine Witze mehr zu machen sondern das Leben, die Welt, mich ernst zu nehmen, aber da ist eine gro\u00dfe Angst&#8230;und ich bef\u00fcrchte, dass hinter dieser Angst eine so gro\u00dfe Wut ist, eine Wut, die so gro\u00df ist das ich Amok laufen k\u00f6nnte, jemanden umbringen k\u00f6nnte&#8230;<\/p>\n<p>Sie schrieben einmal \u00fcber Buster Keaton, die Geschichte ist ersch\u00fctternd, von Michael Jackson will ich erst gar nicht anfangen&#8230; Der ganze Show und Unterhaltungszirkus zerplatzt wie eine Seifenblase wenn man f\u00fchlenden Zugang zu den wirklichen Geschichten bekommt.<br \/>\nAber auch in der Hochkultur, Literatur l\u00e4uft das ja. Ich habe den Eindruck die Autoren, die am besten Verdr\u00e4ngen, bekommen (daf\u00fcr etwa&#8230;?) die gr\u00f6\u00dften Preise&#8230;<br \/>\nSie schreiben \u00fcber die Irische Mentalit\u00e4t am Beispiel Mc Court, es ist wirklich eine Hilfe diese Sicht zu lesen etwa auf das Thema Ironie, Sarkasmus&#8230;. Bei so vielem in der Kunst denke ich nur noch &#8222;Drogen-Musik&#8220; (Pink-Floyd) pubert\u00e4r (Actionkino), infantil (Helge Schneider) Neurotisch (die ganz Comedy-Welt) und so weiter&#8230;<\/p>\n<p>Ich bin 42 Jahre alt und habe eine 12 j\u00e4hrigen Sohn. \u00dcberhaupt die Vaterschaft, mich daran zu freuen, es zu genie\u00dfen.. ging ganz lange nur so wenig&#8230; (gerade die Clowns, sind ja alles selbst noch Kinder&#8230;) und doch kann ich sagen es gibt Fortschritte. Ich muss vieles nicht mehr an meinen Sohn weitergeben. Dar\u00fcber bin ich sehr froh!<\/p>\n<p>Herzlichst gr\u00fc\u00dfend,TK<\/p><\/div>\n<div class=\"colonne-gauche\">\n<ul class=\"lcp_catlist\" id=\"lcp_instance_0\"><li class=\"current\"><a href=\"http:\/\/www.alice-miller.com\/de\/ironie-als-abwehr\/\">Ironie als Abwehr<\/a><\/li><li><a href=\"http:\/\/www.alice-miller.com\/de\/horbuch\/\">H\u00d6RBUCH<\/a><\/li><li><a href=\"http:\/\/www.alice-miller.com\/de\/zitat-nach-hr-5-10-09\/\">Zitat nach HR, 5.10.09<\/a><\/li><li><a href=\"http:\/\/www.alice-miller.com\/de\/introductione-in-italiano\/\">Introductione in Italiano<\/a><\/li><li><a href=\"http:\/\/www.alice-miller.com\/de\/dein-gerettetes-leben-ist-erschienen\/\">&#8222;Dein gerettetes Leben&#8220; ist erschienen<\/a><\/li><li><a href=\"http:\/\/www.alice-miller.com\/de\/bilder-meines-lebens\/\">&#8222;Bilder meines Lebens&#8220;<\/a><\/li><\/ul>\n<div class=\"separateur\">&nbsp;<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Friday 05 March 2010 Ironie als Abwehr Sehr geehrte Frau Miller, vielen Dank einmal f\u00fcr all ihre B\u00fccher. Sie sind eine Art Gesundbrunnen f\u00fcr mich, trostspendend, eine gro\u00dfe Hilfe. Das erste von vielen &#8222;Therapie- und Psychologieb\u00fcchern&#8220; in meinem Leben war das Drama-Buch, wobei ich sagen muss, dass ich mich zun\u00e4chst gar nicht angesprochen gef\u00fchlt hatte, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-65","post","type-post","status-publish","format-standard","hentry","category-editorial"],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":1,"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":66,"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/posts\/65\/revisions\/66"}],"wp:attachment":[{"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.alice-miller.com\/de\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}